{"id":7205,"date":"2022-01-24T05:12:00","date_gmt":"2022-01-24T05:12:00","guid":{"rendered":"https:\/\/prettylinks.com\/?p=7205"},"modified":"2022-01-20T15:44:37","modified_gmt":"2022-01-20T15:44:37","slug":"online-communities-brand-awareness-attract-new-customers","status":"publish","type":"post","link":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/","title":{"rendered":"Como ampliar o conhecimento de sua marca e atrair novos clientes com comunidades on-line"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Conte\u00fado<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57d209dc3ad\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57d209dc3ad\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#What_are_Online_Communities_and_Why_You_Should_Consider_Making_One\" >O que s\u00e3o comunidades on-line (e por que voc\u00ea deve pensar em criar uma)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#How_to_Start_and_Grow_Your_Own_Online_Community_In_4_Steps\" >Como iniciar e desenvolver sua pr\u00f3pria comunidade on-line (em 4 etapas)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#Step_1_Plan_Your_Community\" >Etapa 1 Planeje sua comunidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#Step_2_Define_Community_Rules_and_Guidelines\" >Etapa 2 Definir regras e diretrizes da comunidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#Step_3_Set_Up_Your_Community\" >Etapa 3 Configure sua comunidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#Step_4_Grow_Your_Community\" >Etapa 4 Desenvolva sua comunidade<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#Conclusion\" >Conclus\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">N\u00e3o \u00e9 poss\u00edvel administrar um neg\u00f3cio bem-sucedido esperando que os clientes o notem. Provavelmente, voc\u00ea precisar\u00e1 aumentar seu p\u00fablico e fortalecer o reconhecimento de sua marca. Entretanto, esse pode ser um processo longo e confuso. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A conex\u00e3o com os clientes por meio de comunidades on-line pode agilizar esse processo. As redes on-line conectam sua empresa a um p\u00fablico que compartilha seus interesses. O envolvimento positivo nas comunidades gera confian\u00e7a em seus clientes e pode aumentar sua receita. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste artigo, exploraremos alguns tipos diferentes de comunidades on-line e os benef\u00edcios que elas podem trazer para sua empresa. Em seguida, voc\u00ea aprender\u00e1 como iniciar sua pr\u00f3pria comunidade e desenvolv\u00ea-la usando <a href=\"https:\/\/prettylinks.com\/pt\/about\/\" target=\"_blank\" rel=\"noreferrer noopener\">nosso plug-in PrettyLinks<\/a>. Vamos come\u00e7ar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"What_are_Online_Communities_and_Why_You_Should_Consider_Making_One\"><\/span>O que s\u00e3o comunidades on-line (e por que voc\u00ea deve pensar em criar uma)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma comunidade on-line \u00e9 um grupo de pessoas com interesses ou valores compartilhados que usam a Internet para se comunicar. Essas redes existem em muitas plataformas, como o Facebook:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/online-community-facebook-groups-1024x659.png\" alt=\"Exemplos de comunidades on-line no Facebook. \" class=\"wp-image-7206\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/online-community-facebook-groups-1024x659.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/online-community-facebook-groups-300x193.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/online-community-facebook-groups-768x494.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/online-community-facebook-groups.png 1102w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 tamb\u00e9m <a href=\"https:\/\/memberpress.com\/blog\/5-ways-to-add-unique-value-to-your-membership-community\/\" target=\"_blank\" rel=\"noreferrer noopener\">comunidades on-line baseadas em associa\u00e7\u00e3o<\/a> com processos de inscri\u00e7\u00e3o para membros. Voc\u00ea precisar\u00e1 da aprova\u00e7\u00e3o da comunidade ou pagar uma taxa de assinatura para participar:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/Join-Us-Pilatesology-1024x446.png\" alt=\"\" class=\"wp-image-7224\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/Join-Us-Pilatesology-1024x446.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/Join-Us-Pilatesology-300x131.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/Join-Us-Pilatesology-768x334.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/Join-Us-Pilatesology.png 1505w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Al\u00e9m de seus downloads digitais, o Pilatesology tem uma comunidade de membros onde eles podem interagir uns com os outros.  <\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">As comunidades on-line oferecem suporte a pessoas que precisam de ajuda e permitem que os membros discutam ideias e compartilhem opini\u00f5es. Al\u00e9m disso, elas podem ajudar a defender ideias e disseminar a conscientiza\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, as comunidades on-line s\u00e3o \u00f3timas para seus resultados financeiros. Quase <a href=\"https:\/\/www.martechadvisor.com\/articles\/ux-and-cro\/how-branded-online-communities-can-boost-your-roi\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">dois ter\u00e7os das empresas<\/a> observaram um aumento na receita quando se envolveram com uma rede baseada na Web. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea puder desenvolver sua comunidade, h\u00e1 um grande potencial para <a href=\"https:\/\/prettylinks.com\/pt\/blog\/increase-engagement-conversions\/\" target=\"_blank\" rel=\"noreferrer noopener\">engajamento com seu p\u00fablico<\/a>. Voc\u00ea tamb\u00e9m pode ouvir opini\u00f5es sobre seus produtos ou servi\u00e7os. Com esse feedback, voc\u00ea pode modificar suas ofertas e criar um produto melhor. <a href=\"https:\/\/prettylinks.com\/pt\/blog\/improve-customer-experience\/\" target=\"_blank\" rel=\"noreferrer noopener\">experi\u00eancia do usu\u00e1rio<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, o <a href=\"https:\/\/en.deezercommunity.com\/ideas\" target=\"_blank\" rel=\"noreferrer noopener\">Deezer<\/a><a href=\"https:\/\/en.deezercommunity.com\/ideas\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> <\/a><a href=\"https:\/\/en.deezercommunity.com\/ideas\" target=\"_blank\" rel=\"noreferrer noopener\">comunidade<\/a> pede aos membros que enviem suas ideias para a plataforma de m\u00fasica:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/deezer-community-ideas-1024x574.jpg\" alt=\"A comunidade on-line da Deezer solicita diretamente ideias e feedback dos clientes. \" class=\"wp-image-7208\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/deezer-community-ideas-1024x574.jpg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/deezer-community-ideas-300x168.jpg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/deezer-community-ideas-768x431.jpg 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/deezer-community-ideas.jpg 1426w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a intera\u00e7\u00e3o com os membros da comunidade pode ajudar <a href=\"https:\/\/www.forbes.com\/sites\/theyec\/2019\/12\/03\/how-a-community-can-contribute-to-building-your-online-brand\/?sh=751c7101669a\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Mostre sua experi\u00eancia<\/a>. Voc\u00ea pode criar confian\u00e7a resolvendo os problemas de seus clientes. Por sua vez, voc\u00ea pode transformar seus usu\u00e1rios casuais em clientes fi\u00e9is. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"How_to_Start_and_Grow_Your_Own_Online_Community_In_4_Steps\"><\/span>Como iniciar e desenvolver sua pr\u00f3pria comunidade on-line (em 4 etapas)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea entende os benef\u00edcios, veja como voc\u00ea pode criar sua comunidade on-line em quatro etapas simples.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Step_1_Plan_Your_Community\"><\/span>Etapa 1: Planeje sua comunidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 improv\u00e1vel que sua comunidade seja bem-sucedida sem um <a href=\"https:\/\/www.business2community.com\/social-business\/online-customer-communities-need-purpose-bigger-building-community-01086496\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">plano e objetivo<\/a>. Criar um mapa detalhado das ideias de sua rede on-line pode ajud\u00e1-lo a se concentrar no que sua marca pode oferecer aos membros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Talvez voc\u00ea queira fazer as seguintes perguntas a si mesmo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Quantos membros voc\u00ea deseja ter em sua comunidade?<\/li><li>Qual ser\u00e1 o prop\u00f3sito de sua comunidade?<\/li><li>Quais s\u00e3o as metas para sua comunidade?<\/li><li>Como voc\u00ea oferecer\u00e1 valor aos seus membros?<\/li><li>Que experi\u00eancias voc\u00ea proporcionar\u00e1 aos usu\u00e1rios da sua comunidade?<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Em seguida, voc\u00ea precisar\u00e1 decidir onde hospedar\u00e1 sua comunidade. Um pequeno grupo de profissionais pode preferir interagir por meio de uma m\u00eddia de bate-papo. Se voc\u00ea quiser centenas ou milhares de membros em sua rede, precisar\u00e1 de uma plataforma maior. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, voc\u00ea poderia <a href=\"https:\/\/memberpress.com\/blog\/building-an-online-membership-site-using-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">criar uma \u00e1rea somente para membros<\/a> de seu site com <a href=\"http:\/\/www.memberpress.com\" target=\"_blank\" rel=\"noreferrer noopener\">o plug-in MemberPress<\/a>:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage-1024x480.png\" alt=\"Voc\u00ea pode usar o plug-in MemberPress para criar uma comunidade on-line. \" class=\"wp-image-7209\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage-1024x480.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage-300x141.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage-768x360.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage-1536x720.png 1536w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/memberpress-homepage.png 1870w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por fim, voc\u00ea deve pensar no p\u00fablico-alvo de sua comunidade on-line. Voc\u00ea deve considerar a coleta de dados demogr\u00e1ficos, interesses e necessidades de seus clientes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, voc\u00ea pode coletar dados de clientes por meio de pesquisas usando um servi\u00e7o como o <a href=\"https:\/\/aytm.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Pergunte ao seu mercado-alvo (AYTM)<\/a>:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/aytm-1024x365.png\" alt=\"O Ask Your Target Market \u00e9 um servi\u00e7o de coleta de dados para obter insights sobre os clientes. \" class=\"wp-image-7210\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/aytm-1024x365.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/aytm-300x107.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/aytm-768x274.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/aytm.png 1412w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Usando dados, voc\u00ea poder\u00e1 adaptar sua rede aos usu\u00e1rios pretendidos. Dessa forma, \u00e9 mais prov\u00e1vel que ela seja bem-sucedida. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Step_2_Define_Community_Rules_and_Guidelines\"><\/span>Etapa 2: Definir regras e diretrizes da comunidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Toda comunidade on-line precisa de diretrizes a serem seguidas por seus membros. Elas ajudam a criar um ambiente seguro e acolhedor para todos os seus usu\u00e1rios. Tamb\u00e9m estabelece uma estrutura clara de como sua rede funcionar\u00e1 e orienta os membros sobre o tom do espa\u00e7o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando os membros se inscreverem em sua comunidade, eles concordar\u00e3o com as regras b\u00e1sicas. Se as violarem, os administradores poder\u00e3o expulsar os usu\u00e1rios do grupo:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/verge-community-guidelines-1024x638.jpg\" alt=\"Um exemplo de diretrizes da comunidade do site da comunidade Verge. \" class=\"wp-image-7211\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/verge-community-guidelines-1024x638.jpg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/verge-community-guidelines-300x187.jpg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/verge-community-guidelines-768x479.jpg 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/verge-community-guidelines.jpg 1378w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, talvez voc\u00ea queira restringir palavr\u00f5es e linguagem argumentativa ou hostil. Talvez voc\u00ea tamb\u00e9m precise considerar se permitir\u00e1 que os membros promovam seus produtos e servi\u00e7os em sua comunidade on-line. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ideal \u00e9 encontrar um equil\u00edbrio em suas diretrizes. Voc\u00ea quer dar liberdade suficiente para que os membros possam se expressar e explorar novas ideias. No entanto, voc\u00ea tamb\u00e9m precisa garantir que os membros se sintam confort\u00e1veis e n\u00e3o amea\u00e7ados. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Step_3_Set_Up_Your_Community\"><\/span>Etapa 3: Configure sua comunidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A pr\u00f3xima etapa \u00e9 <a href=\"https:\/\/prettylinks.com\/pt\/blog\/build-online-community\/\" target=\"_blank\" rel=\"noreferrer noopener\">Criando seu site de comunidade<\/a>. \u00c9 aqui que voc\u00ea configurar\u00e1 seu <a href=\"https:\/\/docs.memberpress.com\/article\/172-memberpress-login-page\" target=\"_blank\" rel=\"noreferrer noopener\">processo de login de membro<\/a> e test\u00e1-lo para ter certeza de que est\u00e1 funcionando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m deve considerar a defini\u00e7\u00e3o de fun\u00e7\u00f5es e expectativas para sua equipe. Nomeie um gerente e selecione os membros da equipe para executar as opera\u00e7\u00f5es di\u00e1rias. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, voc\u00ea precisar\u00e1 designar quem ser\u00e1 respons\u00e1vel por moderar as mensagens, lidar com discuss\u00f5es entre os membros da comunidade e manter o spam fora dos f\u00f3runs. Voc\u00ea tamb\u00e9m precisar\u00e1 de uma equipe para criar e carregar o conte\u00fado de acordo com sua programa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, certifique-se de que sua comunidade esteja de acordo com a marca. Muitas plataformas permitem que os grupos adicionem logotipos de empresas e fotos de perfil. Voc\u00ea tamb\u00e9m deve combinar o tom de sua comunidade com o de sua empresa. Se o site de sua empresa for profissional, sua rede tamb\u00e9m dever\u00e1 ser:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/professional-linkedin-group-1024x452.jpg\" alt=\"Um exemplo de um grupo de comunidade on-line profissional. \" class=\"wp-image-7212\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/professional-linkedin-group-1024x452.jpg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/professional-linkedin-group-300x133.jpg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/professional-linkedin-group-768x339.jpg 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/professional-linkedin-group.jpg 1127w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m recomendamos testar sua comunidade antes de lan\u00e7\u00e1-la para os clientes. Resolva quaisquer erros ou falhas para garantir que seu site funcione sem problemas. Considere a possibilidade de usar uma abertura suave, convidando um pequeno grupo de usu\u00e1rios para experimentar sua rede antes de permitir a entrada de mais pessoas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Step_4_Grow_Your_Community\"><\/span>Etapa 4: Aumente sua comunidade<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na maioria dos casos, sua comunidade n\u00e3o crescer\u00e1 rapidamente por conta pr\u00f3pria. Voc\u00ea precisar\u00e1 tomar medidas para promover sua comunidade e incentivar seus membros a participar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode usar os recursos que j\u00e1 tem em m\u00e3os. Encontre informa\u00e7\u00f5es de contato de clientes em seu <a href=\"https:\/\/prettylinks.com\/pt\/blog\/build-a-powerful-email-list-to-promote-your-affiliate-offers\/\" target=\"_blank\" rel=\"noreferrer noopener\">lista de e-mail<\/a> e as pessoas que interagem com sua empresa em <a href=\"https:\/\/prettylinks.com\/pt\/blog\/social-media-marketing-business\/\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00eddia social<\/a>. Voc\u00ea pode pedir a eles que se juntem \u00e0 sua nova comunidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tamb\u00e9m deve considerar a cria\u00e7\u00e3o de um cronograma de conte\u00fado. Se os membros considerarem suas publica\u00e7\u00f5es valiosas, provavelmente continuar\u00e3o a usar sua comunidade. N\u00e3o encha sua rede com postagens in\u00fateis ou fora do assunto. Em vez disso, considere publicar informa\u00e7\u00f5es e conte\u00fado de alta qualidade relacionados ao seu neg\u00f3cio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, certifique-se de que est\u00e1 publicando conte\u00fado de forma consistente. Quando os usu\u00e1rios sabem o que esperar, \u00e9 mais prov\u00e1vel que retornem. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, voc\u00ea pode usar <a href=\"https:\/\/prettylinks.com\/pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">nosso plug-in PrettyLinks<\/a> para expandir sua comunidade e aumentar a receita. Ele permite que voc\u00ea converta URLs longos e complicados em <a href=\"https:\/\/prettylinks.com\/pt\/blog\/how-to-use-pretty-links-plugin\/\" target=\"_blank\" rel=\"noreferrer noopener\">links curtos, atraentes e informativos<\/a>:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-1024x463.png\" alt=\"Criando um link bonito com o plug-in PrettyLinks. \" class=\"wp-image-5977\" width=\"800\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-1024x463.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-300x136.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-768x347.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-1536x695.png 1536w, https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/03\/pretty-links-cloaking-2048x926.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, voc\u00ea pode criar um novo URL para o site da sua comunidade. Em seguida, pode promov\u00ea-lo em suas m\u00eddias sociais e plataformas de marketing. Dessa forma, voc\u00ea pode atrair novos usu\u00e1rios e criar sua rede. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Encontrar clientes novos e fi\u00e9is para sua empresa n\u00e3o \u00e9 f\u00e1cil. Ao criar uma comunidade on-line, voc\u00ea pode se conectar com mais pessoas do seu p\u00fablico-alvo, aumentar o conhecimento da marca e promover seus produtos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para criar e desenvolver sua pr\u00f3pria comunidade on-line, voc\u00ea precisar\u00e1:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Planeje sua rede on-line.<\/li><li>Defina as regras e diretrizes de sua comunidade.<\/li><li>Configure sua comunidade.<\/li><li>Aumente sua rede on-line.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Voc\u00ea tem alguma d\u00favida sobre como criar uma comunidade on-line?<\/em>? Deixe-nos saber na se\u00e7\u00e3o de coment\u00e1rios!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea gostou deste artigo, n\u00e3o deixe de nos seguir em <a href=\"https:\/\/www.facebook.com\/prettylink\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Facebook<\/strong><\/a>, <a href=\"https:\/\/twitter.com\/prettylink?lang=en\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Twitter<\/strong><\/a>, <a href=\"https:\/\/www.pinterest.com\/memberpressplugin\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pinterest<\/strong><\/a>e <a href=\"https:\/\/www.linkedin.com\/showcase\/pretty-links\/?viewAsMember=true\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>LinkedIn<\/strong><\/a>! E n\u00e3o se esque\u00e7a de se inscrever no <a href=\"https:\/\/prettylinks.com\/go\/box\/\" title=\"Link de afiliado da caixa\" class=\"pretty-link-keyword\"rel=\"nofollow \" target=\"_blank\">caixa<\/a> abaixo.<\/p>","protected":false},"excerpt":{"rendered":"<p>N\u00e3o \u00e9 poss\u00edvel administrar um neg\u00f3cio bem-sucedido esperando que os clientes o notem. Provavelmente, voc\u00ea precisar\u00e1 aumentar seu p\u00fablico e fortalecer o reconhecimento de sua marca. No entanto, esse pode ser um processo longo e confuso. A conex\u00e3o com os clientes por meio de comunidades on-line pode simplificar esse processo. As redes on-line conectam sua empresa a um p\u00fablico que compartilha...<\/p>","protected":false},"author":11450,"featured_media":7225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[47,11],"tags":[409,486],"class_list":["post-7205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-tos","category-marketing","tag-memberpress","tag-online-community"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"John Hughes\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"PrettyLinks\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\" \/>\n\t\t<meta property=\"og:description\" content=\"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1448\" \/>\n\t\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-01-24T05:12:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-20T15:44:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#blogposting\",\"name\":\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\",\"headline\":\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\",\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/iStock-936130080.jpg\",\"width\":1448,\"height\":724,\"caption\":\"Online Communities_PrettyLinks\"},\"datePublished\":\"2022-01-24T05:12:00-07:00\",\"dateModified\":\"2022-01-20T15:44:37-07:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#webpage\"},\"articleSection\":\"How Tos, Marketing, MemberPress, online community\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/pt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/category\\\/marketing\\\/#listItem\",\"name\":\"Marketing\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/category\\\/marketing\\\/#listItem\",\"position\":2,\"name\":\"Marketing\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/category\\\/marketing\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#listItem\",\"name\":\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#listItem\",\"position\":3,\"name\":\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/category\\\/marketing\\\/#listItem\",\"name\":\"Marketing\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/#organization\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/author\\\/johnwordcandy-co\\\/\",\"name\":\"John Hughes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#authorImage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1783709960\",\"width\":96,\"height\":96,\"caption\":\"John Hughes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#webpage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/\",\"name\":\"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities\",\"description\":\"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/iStock-936130080.jpg\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#mainImage\",\"width\":1448,\"height\":724,\"caption\":\"Online Communities_PrettyLinks\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/blog\\\/online-communities-brand-awareness-attract-new-customers\\\/#mainImage\"},\"datePublished\":\"2022-01-24T05:12:00-07:00\",\"dateModified\":\"2022-01-20T15:44:37-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>How to Broaden Your Brand Awareness and Attract New Customers with Online Communities<\/title>\n\n","aioseo_head_json":{"title":"Como ampliar o conhecimento de sua marca e atrair novos clientes com comunidades on-line","description":"Est\u00e1 procurando ampliar o conhecimento da sua marca e atrair novos clientes? Saiba como iniciar e desenvolver comunidades on-line de sucesso em quatro etapas f\u00e1ceis!","canonical_url":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#blogposting","name":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","headline":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","author":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/author\/johnwordcandy-co\/#author"},"publisher":{"@id":"https:\/\/prettylinks.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg","width":1448,"height":724,"caption":"Online Communities_PrettyLinks"},"datePublished":"2022-01-24T05:12:00-07:00","dateModified":"2022-01-20T15:44:37-07:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#webpage"},"isPartOf":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#webpage"},"articleSection":"How Tos, Marketing, MemberPress, online community"},{"@type":"BreadcrumbList","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt#listItem","position":1,"name":"Home","item":"https:\/\/prettylinks.com\/pt","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt\/blog\/category\/marketing\/#listItem","name":"Marketing"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt\/blog\/category\/marketing\/#listItem","position":2,"name":"Marketing","item":"https:\/\/prettylinks.com\/pt\/blog\/category\/marketing\/","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#listItem","name":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities"},"previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#listItem","position":3,"name":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/pt\/blog\/category\/marketing\/#listItem","name":"Marketing"}}]},{"@type":"Organization","@id":"https:\/\/prettylinks.com\/pt\/#organization","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","url":"https:\/\/prettylinks.com\/pt\/"},{"@type":"Person","@id":"https:\/\/prettylinks.com\/pt\/blog\/author\/johnwordcandy-co\/#author","url":"https:\/\/prettylinks.com\/pt\/blog\/author\/johnwordcandy-co\/","name":"John Hughes","image":{"@type":"ImageObject","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#authorImage","url":"https:\/\/prettylinks.com\/wp-content\/litespeed\/avatar\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1783709960","width":96,"height":96,"caption":"John Hughes"}},{"@type":"WebPage","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#webpage","url":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/","name":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","description":"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/prettylinks.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#breadcrumblist"},"author":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/author\/johnwordcandy-co\/#author"},"creator":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/author\/johnwordcandy-co\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg","@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#mainImage","width":1448,"height":724,"caption":"Online Communities_PrettyLinks"},"primaryImageOfPage":{"@id":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/#mainImage"},"datePublished":"2022-01-24T05:12:00-07:00","dateModified":"2022-01-20T15:44:37-07:00"},{"@type":"WebSite","@id":"https:\/\/prettylinks.com\/pt\/#website","url":"https:\/\/prettylinks.com\/pt\/","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/prettylinks.com\/pt\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"PrettyLinks","og:type":"article","og:title":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","og:description":"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!","og:url":"https:\/\/prettylinks.com\/pt\/blog\/online-communities-brand-awareness-attract-new-customers\/","og:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg","og:image:secure_url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg","og:image:width":1448,"og:image:height":724,"article:published_time":"2022-01-24T05:12:00+00:00","article:modified_time":"2022-01-20T15:44:37+00:00","twitter:card":"summary_large_image","twitter:title":"How to Broaden Your Brand Awareness and Attract New Customers with Online Communities","twitter:description":"Are you looking to broaden your brand awareness and attract new customers? Learn how to start and grow successful online communities in four easy steps!","twitter:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2021\/09\/iStock-936130080.jpg"},"aioseo_meta_data":{"post_id":"7205","title":null,"description":"Est\u00e1 procurando ampliar o conhecimento da sua marca e atrair novos clientes? Saiba como iniciar e desenvolver comunidades on-line de sucesso em quatro etapas f\u00e1ceis!","keywords":[{"label":"online community ","value":"online community "},{"label":"membership program","value":"membership program"}],"keyphrases":{"focus":{"keyphrase":"Online Communities","score":80,"analysis":{"keyphraseInTitle":{"title":"Focus Keyphrase in SEO title","description":"Focus Keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"title":"Focus keyphrase in meta description","description":"Focus keyphrase found in meta description.","score":9,"maxScore":9,"error":0},"keyphraseInURL":{"title":"Focus Keyphrase in URL","description":"Focus Keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase does not appear in the first paragraph. Make sure the topic is clear immediately.","score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"title":"Focus Keyphrase in Subheadings","description":"Use more focus keyphrases in your H2 and H3 subheadings!","score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase found in image alt attribute(s).","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-09 19:11:40","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-09-21 16:40:47","updated":"2026-06-09 19:11:40"},"_links":{"self":[{"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/posts\/7205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/users\/11450"}],"replies":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/comments?post=7205"}],"version-history":[{"count":0,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/posts\/7205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/media\/7225"}],"wp:attachment":[{"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/media?parent=7205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/categories?post=7205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prettylinks.com\/pt\/wp-json\/wp\/v2\/tags?post=7205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}