{"id":3151,"date":"2018-11-02T16:17:12","date_gmt":"2018-11-02T16:17:12","guid":{"rendered":"https:\/\/prettylinks.com\/?p=3151"},"modified":"2018-11-02T16:17:12","modified_gmt":"2018-11-02T16:17:12","slug":"new-top-level-domains-tlds","status":"publish","type":"post","link":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/","title":{"rendered":"Introducci\u00f3n a los nuevos dominios de nivel superior (TLD)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a98614fbce07\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a98614fbce07\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#A_Brief_Introduction_to_Top-Level_Domains_TLDs\" >Breve introducci\u00f3n a los dominios de primer nivel (TLD)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#What_the_New_TLDs_Are\" >Qu\u00e9 son los nuevos TLD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#Why_You_Might_Want_to_Use_a_New_TLD\" >\u00bfPor qu\u00e9 le conviene utilizar un nuevo TLD?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#How_to_Register_a_New_TLD\" >C\u00f3mo registrar un nuevo TLD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<p>Hasta hace poco, sus opciones eran limitadas a la hora de elegir el dominio de nivel superior (TLD) de su sitio web. Sin embargo, hace tan solo unos a\u00f1os, esto cambi\u00f3 radicalmente cuando se pusieron a disposici\u00f3n de los usuarios toda una serie de nuevos TLD para registrar.<\/p>\n<p>Desde que se abrieron las compuertas, se han lanzado literalmente cientos de nuevos TLD. Esto significa que ahora puede beneficiarse de opciones de dominio muy ampliadas, lo que tambi\u00e9n ayuda a crear nombres de dominio de marca y URL de vanidad.<\/p>\n<p>En este art\u00edculo, analizaremos estos nuevos TLD y sus ventajas e inconvenientes. Tambi\u00e9n le mostraremos algunos ejemplos y le ayudaremos a decidir si deber\u00eda plantearse utilizar uno de ellos. Empecemos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_Brief_Introduction_to_Top-Level_Domains_TLDs\"><\/span>Breve introducci\u00f3n a los dominios de primer nivel (TLD)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aunque no est\u00e9 familiarizado con el t\u00e9rmino\u00a0<a href=\"https:\/\/en.wikipedia.org\/wiki\/Top-level_domain\" target=\"_blank\" rel=\"noopener\">Dominio de primer nivel (TLD)<\/a>seguro que lo ha visto en acci\u00f3n. El TLD es la extensi\u00f3n que aparece al final del nombre de dominio de su sitio, como por ejemplo\u00a0<em>.com<\/em>.<\/p>\n<p>En <em>.com<\/em> es, con diferencia, el <a href=\"https:\/\/www.lifewire.com\/most-common-tlds-internet-domain-extensions-817511\" target=\"_blank\" rel=\"noopener\">TLD m\u00e1s com\u00fan<\/a>hay <a href=\"https:\/\/w3techs.com\/technologies\/overview\/top_level_domain\/all\" target=\"_blank\" rel=\"noopener\">varios otros<\/a> que probablemente conozca, como <em>.net<\/em>, <em>.org<\/em>y <em>.edu<\/em>. Sin embargo, aunque estos representan los TLD m\u00e1s populares, no son ni mucho menos los \u00fanicos. De hecho, el conjunto de TLD disponibles se ha ampliado recientemente de forma espectacular, ya que se han puesto a disposici\u00f3n cientos de nuevas opciones.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"What_the_New_TLDs_Are\"><\/span>Qu\u00e9 son los nuevos TLD<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Las nuevas opciones de extensi\u00f3n de dominio son el resultado de la\u00a0<a href=\"http:\/\/newgtlds.icann.org\/en\/about\/program\" target=\"_blank\" rel=\"noopener\">Nuevo gTLD<\/a> programa. Se trataba de una iniciativa dise\u00f1ada para ampliar el n\u00famero de TLD disponibles. El proceso comenz\u00f3 en 2005, pero el programa propiamente dicho arranc\u00f3 en 2012, cuando la Corporaci\u00f3n de Asignaci\u00f3n de Nombres y N\u00fameros de Internet (ICANN) empez\u00f3 a aceptar propuestas de nuevos TLD.<\/p>\n<p>Tras recibir <a href=\"http:\/\/newgtlds.icann.org\/en\/announcements-and-media\/announcement-13jun12-en\" target=\"_blank\" rel=\"noopener\">1.930 solicitudes<\/a>, ICANN comenz\u00f3 a lanzar nuevos TLD en 2013. Desde entonces, m\u00e1s de mil <a href=\"https:\/\/newgtlds.icann.org\/en\/program-status\/delegated-strings\" target=\"_blank\" rel=\"noopener\">Se han aprobado los TLD<\/a>La m\u00e1s reciente se lanz\u00f3 en junio de 2018. Algunas de las nuevas incorporaciones que han ganado m\u00e1s popularidad son las siguientes <em>.xyz<\/em>, <em>.blog<\/em>y <em>.club<\/em>.<\/p>\n<p>Varios de los TLD aprobados destacan especialmente por el uso de caracteres no latinos. Por ejemplo, una de las primeras opciones en ponerse en marcha fue <em>.\u043e\u043d\u043b\u0430\u0439\u043d<\/em>que en ruso significa \"en l\u00ednea\". Esta medida abrir\u00e1 Internet a\u00fan m\u00e1s a las regiones que no hablan ingl\u00e9s ni lat\u00edn.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Why_You_Might_Want_to_Use_a_New_TLD\"><\/span>\u00bfPor qu\u00e9 le conviene utilizar un nuevo TLD?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Al abrirse las compuertas para los TLD, ahora hay m\u00e1s opciones que nunca para quienes desean comprar un dominio. Adem\u00e1s, existen varias formas de beneficiarse del uso de un nuevo TLD en lugar de una opci\u00f3n tradicional.<\/p>\n<p>Por ejemplo, los nuevos TLD pueden ser:<\/p>\n<ul>\n<li><strong>M\u00e1s barato comprar.<\/strong>\u00a0Muchos de los nuevos TLD suelen ser bastante m\u00e1s baratos que las opciones est\u00e1ndar. Por ejemplo, puede obtener un <em>.xyz<\/em> o <em>.site<\/em> dominio para <a href=\"https:\/\/tld-list.com\/\" target=\"_blank\" rel=\"noopener\">menos de $1<\/a> durante el primer a\u00f1o, con tasas de renovaci\u00f3n por debajo de $10.<\/li>\n<li><strong>M\u00e1s descriptivo.<\/strong> Utilizar un TLD que coincida con el prop\u00f3sito de su sitio puede ayudar a mejorar su imagen de marca y hacer que su URL sea m\u00e1s f\u00e1cil de recordar. Algunos ejemplos <em>.blog<\/em> y\u00a0<em>.tienda<\/em>que muestran claramente el prop\u00f3sito del sitio en la URL.<\/li>\n<li><strong>Mejor para <a href=\"https:\/\/prettylinks.com\/es\/blog\/3-reasons-you-should-brand-your-links\/\" target=\"_blank\" rel=\"noopener\">enlaces de marca<\/a>.<\/strong> Con un nuevo TLD, tiene m\u00e1s libertad a la hora de crear enlaces de marca y <a href=\"https:\/\/prettylinks.com\/es\/blog\/how-to-boost-your-brand-power-with-vanity-urls\/\" target=\"_blank\" rel=\"noopener\">URL de vanidad<\/a>.<\/li>\n<\/ul>\n<p>Sin embargo, esto no quiere decir que estos TLD no tengan inconvenientes. Uno de ellos es que, al ser relativamente nuevos, muchos internautas est\u00e1n menos familiarizados con ellos, lo que hace que parezcan... <a href=\"https:\/\/varn.co.uk\/10\/27\/70-of-people-dont-trust-newer-website-domains\/\" target=\"_blank\" rel=\"noopener\">menos fiable<\/a>. Sin embargo, es probable que esto cambie a medida que estas opciones se generalicen y sean utilizadas por marcas conocidas. De hecho, la propia Google utiliza\u00a0<em>.xyz<\/em>\u00a0para la <a href=\"https:\/\/abc.xyz\/\" target=\"_blank\" rel=\"noopener\">su empresa matriz Alphabet<\/a>.<\/p>\n<p>Otra consideraci\u00f3n importante es c\u00f3mo puede afectar un nuevo TLD a su imagen de marca. Si se dirige a un p\u00fablico m\u00e1s joven, un nuevo TLD puede parecer menos \"estirado\" que una opci\u00f3n est\u00e1ndar. Por el contrario, si su sitio es de naturaleza m\u00e1s tradicional, utilizar un TLD est\u00e1ndar puede parecer m\u00e1s profesional. En \u00faltima instancia, tanto los TLD nuevos como los antiguos pueden ser la elecci\u00f3n correcta, dependiendo del enfoque de su sitio y de su p\u00fablico principal.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"How_to_Register_a_New_TLD\"><\/span>C\u00f3mo registrar un nuevo TLD<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si ha decidido que le gustar\u00eda probar uno de los nuevos TLD, tiene muchas opciones. Adem\u00e1s, el proceso de obtenci\u00f3n de un nuevo TLD no difiere del de compra de cualquiera de los antiguos. Obtener un nombre de dominio con un nuevo TLD es tan sencillo como buscar un registrador de dominios que los suministre y encontrar uno que se ajuste a su marca y requisitos.<\/p>\n<p>Por ejemplo, si desea un <em>.xyz<\/em> puede buscar y comprar uno directamente en el sitio web del TLD. <a href=\"http:\/\/xyz.com\/\" target=\"_blank\" rel=\"noopener\">sitio oficial<\/a>:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3152\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search.png\" alt=\"El sitio web xyz.com.\" width=\"800\" height=\"254\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search.png 3360w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search-300x95.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search-1024x325.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search-768x244.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search-1536x487.png 1536w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-domain-search-2048x650.png 2048w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Sin embargo, tambi\u00e9n hay registradores especializados en ofrecer muchos nuevos TLD diferentes, como por ejemplo\u00a0<a href=\"https:\/\/www.centralnic.com\/portfolio\/newtlds\" target=\"_blank\" rel=\"noopener\">CentralNic<\/a>:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3153\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds.png\" alt=\"P\u00e1gina web de CentralNic.\" width=\"800\" height=\"502\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds.png 2336w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds-300x188.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds-1024x643.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds-768x482.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds-1536x964.png 1536w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/centralnic-new-tlds-2048x1285.png 2048w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Todo lo que tiene que hacer es buscar el dominio que desea. Una vez que lo hayas encontrado, puedes a\u00f1adirlo a tu cesta y comprarlo como lo har\u00edas <a href=\"https:\/\/www.dreamhost.com\/blog\/beginners-guide-domain-name-registration\/\" target=\"_blank\" rel=\"noopener\">cualquier otro nombre de dominio<\/a>:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3154\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart.png\" alt=\"A\u00f1adir un nombre de dominio xyz a su cesta.\" width=\"800\" height=\"383\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart.png 1768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart-300x144.png 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart-1024x490.png 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart-768x367.png 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/10\/xyz-add-to-cart-1536x735.png 1536w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Una vez realizada la compra, podr\u00e1 conectar el dominio a su sitio web. Podr\u00e1 utilizarlo para <a href=\"https:\/\/prettylinks.com\/es\/blog\/how-to-boost-your-brand-power-with-vanity-urls\/\" target=\"_blank\" rel=\"noopener\">personalice su sitio web<\/a>o crear un <a href=\"https:\/\/prettylinks.com\/es\/docs\/shortlink-url\/\" target=\"_blank\" rel=\"noopener\">Enlace URL<\/a>. Puede que incluso desee utilizar varios nombres de dominio diferentes para distintos aspectos de su sitio; por ejemplo, puede utilizar un <em>.blog<\/em> para el blog de su sitio web. El \u00fanico l\u00edmite para el uso de estos nuevos TLD es su propia creatividad.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Los d\u00edas en los que b\u00e1sicamente ten\u00edas que elegir entre <em>.com<\/em> y <em>.net<\/em> hace tiempo que desaparecieron. Con la llegada de cientos de nuevos TLD, ahora tiene un enorme grado de libertad a la hora de elegir un nombre de dominio. Esto le permite crear enlaces de marca a\u00fan mejores y dar rienda suelta a su creatividad a la hora de nombrar su sitio web.<\/p>\n<p>Por supuesto, los nuevos TLD presentan ventajas e inconvenientes. Por un lado, todav\u00eda existe la sensaci\u00f3n generalizada de que son menos fiables que las alternativas est\u00e1ndar. Sin embargo, tambi\u00e9n suelen ser bastante m\u00e1s baratos que sus hom\u00f3logos tradicionales y ofrecen muchas m\u00e1s posibilidades de marca.<\/p>\n<p>\u00bfTiene alguna pregunta sobre si deber\u00eda utilizar un nuevo TLD para su sitio? H\u00e1ganoslo saber en la secci\u00f3n de comentarios.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hasta hace poco, sus opciones eran limitadas a la hora de elegir el dominio de nivel superior (TLD) de su sitio web. Sin embargo, hace s\u00f3lo unos a\u00f1os, esta situaci\u00f3n cambi\u00f3 radicalmente cuando se pusieron a disposici\u00f3n de los usuarios toda una serie de nuevos TLD para su registro. Desde que se abrieron las compuertas, se han lanzado literalmente cientos de nuevos TLD. Esto significa que ahora puede beneficiarse...<\/p>","protected":false},"author":11450,"featured_media":3173,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_strive_editorial_status":"not-started","_strive_copy_of":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[6],"tags":[40,41,145],"class_list":["post-3151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branding","tag-domain","tag-domain-registration","tag-top-level-domains"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Your options for Top-Level Domains used to be limited, but that&#039;s no longer the case. Let&#039;s talk about the new TLD options, and how they can be useful!\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"John Hughes\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"PrettyLinks\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"An Introduction to the New Top-Level Domains (TLDs)\" \/>\n\t\t<meta property=\"og:description\" content=\"Your options for Top-Level Domains used to be limited, but that&#039;s no longer the case. Let&#039;s talk about the new TLD options, and how they can be useful!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1480\" \/>\n\t\t<meta property=\"og:image:height\" content=\"987\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-11-02T16:17:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-11-02T16:17:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"An Introduction to the New Top-Level Domains (TLDs)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Your options for Top-Level Domains used to be limited, but that&#039;s no longer the case. Let&#039;s talk about the new TLD options, and how they can be useful!\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#blogposting\",\"name\":\"An Introduction to the New Top-Level Domains (TLDs)\",\"headline\":\"An Introduction to the New Top-Level Domains (TLDs)\",\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Top-Level-Domains@2x.png\",\"width\":1480,\"height\":987},\"datePublished\":\"2018-11-02T16:17:12-06:00\",\"dateModified\":\"2018-11-02T16:17:12-06:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#webpage\"},\"articleSection\":\"Branding, domain, domain registration, top-level domains\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/category\\\/branding\\\/#listItem\",\"name\":\"Branding\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/category\\\/branding\\\/#listItem\",\"position\":2,\"name\":\"Branding\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/category\\\/branding\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#listItem\",\"name\":\"An Introduction to the New Top-Level Domains (TLDs)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#listItem\",\"position\":3,\"name\":\"An Introduction to the New Top-Level Domains (TLDs)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/category\\\/branding\\\/#listItem\",\"name\":\"Branding\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/#organization\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/author\\\/johnwordcandy-co\\\/\",\"name\":\"John Hughes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#authorImage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1787943643\",\"width\":96,\"height\":96,\"caption\":\"John Hughes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#webpage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/\",\"name\":\"An Introduction to the New Top-Level Domains (TLDs)\",\"description\":\"Your options for Top-Level Domains used to be limited, but that's no longer the case. Let's talk about the new TLD options, and how they can be useful!\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/Top-Level-Domains@2x.png\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#mainImage\",\"width\":1480,\"height\":987},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/blog\\\/new-top-level-domains-tlds\\\/#mainImage\"},\"datePublished\":\"2018-11-02T16:17:12-06:00\",\"dateModified\":\"2018-11-02T16:17:12-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>An Introduction to the New Top-Level Domains (TLDs)<\/title>\n\n","aioseo_head_json":{"title":"Introducci\u00f3n a los nuevos dominios de nivel superior (TLD)","description":"Las opciones de dominios de nivel superior sol\u00edan ser limitadas, pero ya no es as\u00ed. Hablemos de las nuevas opciones de TLD y de su utilidad.","canonical_url":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#blogposting","name":"An Introduction to the New Top-Level Domains (TLDs)","headline":"An Introduction to the New Top-Level Domains (TLDs)","author":{"@id":"https:\/\/prettylinks.com\/es\/blog\/author\/johnwordcandy-co\/#author"},"publisher":{"@id":"https:\/\/prettylinks.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png","width":1480,"height":987},"datePublished":"2018-11-02T16:17:12-06:00","dateModified":"2018-11-02T16:17:12-06:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#webpage"},"isPartOf":{"@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#webpage"},"articleSection":"Branding, domain, domain registration, top-level domains"},{"@type":"BreadcrumbList","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/prettylinks.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es\/blog\/category\/branding\/#listItem","name":"Branding"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es\/blog\/category\/branding\/#listItem","position":2,"name":"Branding","item":"https:\/\/prettylinks.com\/es\/blog\/category\/branding\/","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#listItem","name":"An Introduction to the New Top-Level Domains (TLDs)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#listItem","position":3,"name":"An Introduction to the New Top-Level Domains (TLDs)","previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/es\/blog\/category\/branding\/#listItem","name":"Branding"}}]},{"@type":"Organization","@id":"https:\/\/prettylinks.com\/es\/#organization","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","url":"https:\/\/prettylinks.com\/es\/"},{"@type":"Person","@id":"https:\/\/prettylinks.com\/es\/blog\/author\/johnwordcandy-co\/#author","url":"https:\/\/prettylinks.com\/es\/blog\/author\/johnwordcandy-co\/","name":"John Hughes","image":{"@type":"ImageObject","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#authorImage","url":"https:\/\/prettylinks.com\/wp-content\/litespeed\/avatar\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1787943643","width":96,"height":96,"caption":"John Hughes"}},{"@type":"WebPage","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#webpage","url":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/","name":"An Introduction to the New Top-Level Domains (TLDs)","description":"Your options for Top-Level Domains used to be limited, but that's no longer the case. Let's talk about the new TLD options, and how they can be useful!","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/prettylinks.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#breadcrumblist"},"author":{"@id":"https:\/\/prettylinks.com\/es\/blog\/author\/johnwordcandy-co\/#author"},"creator":{"@id":"https:\/\/prettylinks.com\/es\/blog\/author\/johnwordcandy-co\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png","@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#mainImage","width":1480,"height":987},"primaryImageOfPage":{"@id":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/#mainImage"},"datePublished":"2018-11-02T16:17:12-06:00","dateModified":"2018-11-02T16:17:12-06:00"},{"@type":"WebSite","@id":"https:\/\/prettylinks.com\/es\/#website","url":"https:\/\/prettylinks.com\/es\/","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","inLanguage":"es-ES","publisher":{"@id":"https:\/\/prettylinks.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"PrettyLinks","og:type":"article","og:title":"An Introduction to the New Top-Level Domains (TLDs)","og:description":"Your options for Top-Level Domains used to be limited, but that's no longer the case. Let's talk about the new TLD options, and how they can be useful!","og:url":"https:\/\/prettylinks.com\/es\/blog\/new-top-level-domains-tlds\/","og:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png","og:image:secure_url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png","og:image:width":1480,"og:image:height":987,"article:published_time":"2018-11-02T16:17:12+00:00","article:modified_time":"2018-11-02T16:17:12+00:00","twitter:card":"summary_large_image","twitter:title":"An Introduction to the New Top-Level Domains (TLDs)","twitter:description":"Your options for Top-Level Domains used to be limited, but that's no longer the case. Let's talk about the new TLD options, and how they can be useful!","twitter:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/11\/Top-Level-Domains@2x.png"},"aioseo_meta_data":{"post_id":"3151","title":null,"description":"Las opciones de dominios de nivel superior sol\u00edan ser limitadas, pero ya no es as\u00ed. Hablemos de las nuevas opciones de TLD y de su utilidad.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-09 18:19:41","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 17:50:48","updated":"2026-06-09 18:19:41"},"_links":{"self":[{"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/posts\/3151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/users\/11450"}],"replies":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":0,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/media\/3173"}],"wp:attachment":[{"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prettylinks.com\/es\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}