{"id":2574,"date":"2018-01-26T18:32:50","date_gmt":"2018-01-26T18:32:50","guid":{"rendered":"https:\/\/prettylinks.com\/?p=2574"},"modified":"2019-12-30T16:50:46","modified_gmt":"2019-12-30T16:50:46","slug":"downsides-to-shortened-links","status":"publish","type":"post","link":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/","title":{"rendered":"3 Nachteile von verk\u00fcrzten Links (und wie man sie bek\u00e4mpft)"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalt<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97ffe55b083\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97ffe55b083\"  aria-label=\"Umschalten auf\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#3_Downsides_to_Shortened_Links_And_How_to_Combat_Them\" >3 Nachteile von verk\u00fcrzten Links (und wie man sie bek\u00e4mpft)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#1_Internet_Users_Can_Be_Wary_of_Clicking_Through\" >1. Internetnutzer k\u00f6nnen vorsichtig sein, wenn sie sich durchklicken<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#2_They_Can_Create_Long_Redirect_Processes\" >2. Sie k\u00f6nnen lange Umleitungsprozesse erzeugen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#3_The_Links_May_Not_Always_Work\" >3. Die Links funktionieren m\u00f6glicherweise nicht immer<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#How_to_Create_Stellar_Shortened_Links_Using_PrettyLinks\" >Wie man mit PrettyLinks hervorragende verk\u00fcrzte Links erstellt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#Conclusion\" >Schlussfolgerung<\/a><\/li><\/ul><\/nav><\/div>\n<p>Das Teilen von Links ist f\u00fcr viele Blogger, Websitebesitzer und Vermarkter eine Notwendigkeit. Lange Links k\u00f6nnen jedoch klobig, unattraktiv und in manchen F\u00e4llen auch wenig vertrauensw\u00fcrdig sein. Linkverk\u00fcrzer k\u00f6nnen helfen und haben viele Vorteile, aber sie haben auch ihre Schattenseiten. Wenn sie nicht richtig eingesetzt werden, k\u00f6nnen sie die <a href=\"https:\/\/en.wikipedia.org\/wiki\/Click-through_rate\" target=\"_blank\" rel=\"noopener noreferrer\">Click-Through-Raten (CTRs)<\/a> und zu einem R\u00fcckgang des Website-Verkehrs f\u00fchren.<\/p>\n<p>Verk\u00fcrzte Links m\u00fcssen nicht negativ besetzt sein. Wenn sie richtig eingesetzt werden, k\u00f6nnen sie Ihre Verlinkungskampagnen und die Interaktion der Nutzer mit ihnen verbessern. Es kann jedoch sein, dass Sie Ihre derzeitigen Verlinkungspraktiken ein wenig anpassen m\u00fcssen (vor allem in Bezug auf die Art und Weise, wie Sie sie erstellen).<\/p>\n<p>In diesem Beitrag stellen wir Ihnen die drei h\u00e4ufigsten Nachteile von verk\u00fcrzten Links vor. Wir zeigen Ihnen auch, wie Sie jeden Nachteil bek\u00e4mpfen k\u00f6nnen und wie <a href=\"https:\/\/prettylinks.com\/de\/about\/\" target=\"_blank\" rel=\"noopener noreferrer\">PrettyLinks<\/a> kann helfen. Fangen wir an!<\/p>\n<h2><span class=\"ez-toc-section\" id=\"3_Downsides_to_Shortened_Links_And_How_to_Combat_Them\"><\/span>3 Nachteile von verk\u00fcrzten Links (und wie man sie bek\u00e4mpft)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Um das Problem zu l\u00f6sen, ist es zun\u00e4chst wichtig zu verstehen <em>warum <\/em>verk\u00fcrzte Links von den Internetnutzern als negativ angesehen werden und welche Probleme sie verursachen k\u00f6nnen. Schauen wir uns das mal an.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"1_Internet_Users_Can_Be_Wary_of_Clicking_Through\"><\/span>1. Internetnutzer k\u00f6nnen vorsichtig sein, wenn sie sich durchklicken<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_2460\" aria-describedby=\"caption-attachment-2460\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2460\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/10\/spam-posting.jpeg\" alt=\"Ein Beispiel f\u00fcr Spam-Posting\" width=\"800\" height=\"204\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/10\/spam-posting.jpeg 1193w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/10\/spam-posting-300x76.jpeg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/10\/spam-posting-1024x261.jpeg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/10\/spam-posting-768x196.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2460\" class=\"wp-caption-text\">Spammy Links sind im Internet weit verbreitet, auch in Foren und Blog-Kommentaren.<\/figcaption><\/figure>\n<p>Tatsache ist, dass viele <a href=\"https:\/\/www.cyren.com\/blog\/articles\/bank-phishing-scam-is-using-shortened-links\" target=\"_blank\" rel=\"noopener noreferrer\">Spammer setzen auf verk\u00fcrzte Links<\/a> um ihre URL zu verschleiern. Dies kann Internetnutzer verunsichern und sie misstrauisch gegen\u00fcber Links machen, die verd\u00e4chtig aussehen (d. h. nicht markengesch\u00fctzte, nicht beschreibende Links).<\/p>\n<p>Daher ist es besonders wichtig, dass Ihre Links so glaubw\u00fcrdig und authentisch wie m\u00f6glich erscheinen. So geht's:<\/p>\n<ul>\n<li><strong>Verwenden Sie nur gebrandete Links. <\/strong>Zum Beispiel, <em>www.mybrand.com\/blogpost<\/em>. So k\u00f6nnen Sie Ihre Marke - z. B. den Namen Ihrer Website - zu allen Links hinzuf\u00fcgen, um die Glaubw\u00fcrdigkeit zu erh\u00f6hen.<\/li>\n<li><strong>Verwenden Sie <\/strong><a href=\"https:\/\/yoast.com\/slug\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Beschreibungsschnecken<\/strong><\/a><strong>. <\/strong>Pr\u00e4gnante (f\u00fcnf W\u00f6rter oder weniger), beschreibende Slugs vermitteln den Internetnutzern eine Vorstellung davon, was Ihr Link enth\u00e4lt, was die Wahrscheinlichkeit erh\u00f6hen kann, dass sie ihn anklicken. Zum Beispiel, <em>www.mybrand.com\/downsides-shortened-links<\/em>.<\/li>\n<\/ul>\n<p>Anstelle von <em>nur<\/em> Wenn Sie Ihre Links k\u00fcrzer machen, sollten Sie das K\u00fcrzen von Links als eine M\u00f6glichkeit betrachten, Ihre Links benutzerfreundlicher zu gestalten. So stellen Sie sicher, dass Sie attraktive, beschreibende Links erstellen, die die Aufmerksamkeit Ihres Publikums auf sich ziehen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2_They_Can_Create_Long_Redirect_Processes\"><\/span>2. Sie k\u00f6nnen lange Umleitungsprozesse erzeugen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_2576\" aria-describedby=\"caption-attachment-2576\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2576\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1.jpg\" alt=\"Das Dropdown-Men\u00fc PrettyLinks&#039; Umleitung\" width=\"800\" height=\"194\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1.jpg 1675w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1-300x73.jpg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1-1024x248.jpg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1-768x186.jpg 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/link-redirection-options-1-1536x372.jpg 1536w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2576\" class=\"wp-caption-text\">Die Wahl der richtigen Umleitungsoption verbessert die Benutzerfreundlichkeit.<\/figcaption><\/figure>\n<p>Wenn ein normaler Link angeklickt wird, kommt es h\u00e4ufig zu einer oder zwei Weiterleitungen. Kostenlose Verk\u00fcrzungs-Tools filtern Ihre URL durch eine Vielzahl von Weiterleitungen. Diese <a href=\"https:\/\/en.ryte.com\/magazine\/the-xxl-redirect-guide-proper-use-of-redirects\" target=\"_blank\" rel=\"noopener noreferrer\">sich negativ auf die Ladezeit der Seite auswirkt<\/a>und es kann dazu f\u00fchren, dass die Nutzer wegklicken, bevor sie auf der endg\u00fcltigen Seite landen. Der beste Weg, dies zu vermeiden, ist die Verwendung eines speziellen Link-Tools (im Gegensatz zu einem Dienst). Hier finden Sie Tipps, wie Sie dies effektiv tun k\u00f6nnen:<\/p>\n<ul>\n<li><strong>W\u00e4hlen Sie ein Werkzeug mit <\/strong><a href=\"https:\/\/prettylinks.com\/de\/blog\/link-redirect-types\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>verschiedene Weiterleitungsoptionen<\/strong><\/a><strong>. <\/strong>Zum Beispiel, permanente oder <a href=\"https:\/\/prettylinks.com\/de\/blog\/3-reasons-to-use-temporary-redirects-on-your-site-and-how-to-get-started\/\" target=\"_blank\" rel=\"noopener noreferrer\">tempor\u00e4re Weiterleitungen<\/a>. So erhalten Sie Optionen, die Ihren Bed\u00fcrfnissen und denen Ihres Publikums entsprechen.<\/li>\n<li><strong>Verstehen Sie, wann es angebracht ist, jede Umleitung zu verwenden. <\/strong>A <a href=\"https:\/\/prettylinks.com\/de\/blog\/how-to-implement-301-redirects-on-your-website\/\" target=\"_blank\" rel=\"noopener noreferrer\">permanente Umleitung<\/a> ist in den meisten F\u00e4llen am besten. Es ist jedoch gut zu wissen, wann andere Umleitungsarten (wie tempor\u00e4re oder Z\u00e4hlpixel) effektiver w\u00e4ren.<\/li>\n<\/ul>\n<p>Indem Sie den Umleitungspfad selbst w\u00e4hlen, stellen Sie sicher, dass die Besucher Ihrer Website angemessen umgeleitet werden. So werden Ihre Besucher so schnell wie m\u00f6glich zur Ziel-URL geleitet.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3_The_Links_May_Not_Always_Work\"><\/span>3. Die Links funktionieren m\u00f6glicherweise nicht immer<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<figure id=\"attachment_2575\" aria-describedby=\"caption-attachment-2575\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2575\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/kohls-404-1.jpeg\" alt=\"Die 404-Fehlerseite von Kohls\" width=\"800\" height=\"295\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/kohls-404-1.jpeg 1330w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/kohls-404-1-300x111.jpeg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/kohls-404-1-1024x377.jpeg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/kohls-404-1-768x283.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-2575\" class=\"wp-caption-text\">Unzuverl\u00e4ssige Linkverk\u00fcrzer k\u00f6nnen Ladefehler verursachen.<\/figcaption><\/figure>\n<p>Wenn Sie auf einen Link klicken, erwarten Sie, dass er Sie zum gew\u00fcnschten Ziel f\u00fchrt. Mit Linkverk\u00fcrzungsdiensten - wie <a href=\"https:\/\/bitly.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bitly<\/a> und <a href=\"https:\/\/goo.gl\/\" target=\"_blank\" rel=\"noopener noreferrer\">goo.gl<\/a> - das ist nicht immer eine Garantie. Diese Dienste k\u00f6nnen jederzeit abgeschaltet werden, und viele wurden sogar schon <a href=\"https:\/\/blog.mailchimp.com\/url-shorteners-and-blacklists\/\" target=\"_blank\" rel=\"noopener noreferrer\">von Internet-Diensteanbietern (ISPs) auf eine schwarze Liste gesetzt<\/a> in der Vergangenheit.<\/p>\n<p>Um unzuverl\u00e4ssige Dienste zu vermeiden und Verbindungsunterbrechungen zu verhindern, empfehlen wir Ihnen folgende Ma\u00dfnahmen:<\/p>\n<ul>\n<li><strong>Verwenden Sie ein spezielles Verk\u00fcrzungsprogramm und nicht einen Dienst.<\/strong> Auf diese Weise k\u00f6nnen Sie sicher sein, dass Ihre Links <em>immer<\/em> verf\u00fcgbar sein. Nat\u00fcrlich empfehlen wir unsere eigenen <a href=\"https:\/\/prettylinks.com\/de\/about\/\" target=\"_blank\" rel=\"noopener noreferrer\">PrettyLinks<\/a>.<\/li>\n<li><strong>\u00dcberpr\u00fcfen Sie Ihre Links h\u00e4ufig. <\/strong>Unabh\u00e4ngig davon, ob Sie einen Online-Dienst oder ein Tool verwenden, ist es wichtig, dass Sie sicherstellen, dass Ihre Links ordnungsgem\u00e4\u00df funktionieren. Sie k\u00f6nnen dies mit kostenlosen Tools tun wie <a href=\"https:\/\/www.deadlinkchecker.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dead Link Checker<\/a>.<\/li>\n<\/ul>\n<p>Die Links auf Ihrer Website (und \u00fcberall sonst, wo Sie mit Ihrer Marke in Verbindung gebracht werden) liegen in Ihrer Verantwortung. Sie sollten sicherstellen, dass sie immer funktionieren, um eine positive User Experience (UX) zu gew\u00e4hrleisten.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"How_to_Create_Stellar_Shortened_Links_Using_PrettyLinks\"><\/span>Wie man stellare verk\u00fcrzte Links erstellt mit <a href=\"https:\/\/prettylinks.com\/de\/about\/\" target=\"_blank\" rel=\"noopener noreferrer\">PrettyLinks<\/a><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2365\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/09\/pretty-link-pro-2.jpeg\" alt=\"\" width=\"800\" height=\"159\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/09\/pretty-link-pro-2.jpeg 1355w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/09\/pretty-link-pro-2-300x60.jpeg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/09\/pretty-link-pro-2-1024x204.jpeg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/09\/pretty-link-pro-2-768x153.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><a href=\"https:\/\/prettylinks.com\/de\/about\/\" target=\"_blank\" rel=\"noopener noreferrer\">PrettyLinks<\/a> ist ein Tool zum Verk\u00fcrzen von Links, mit dem Sie Ihre Links kennzeichnen, verk\u00fcrzen und verfolgen k\u00f6nnen. Es unterscheidet sich deutlich von <a href=\"https:\/\/bitly.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bitly<\/a> (und \u00e4hnlichen Diensten), da es sich um ein zuverl\u00e4ssiges Werkzeug handelt, das nicht auf einen externen Dienst angewiesen ist.<\/p>\n<p>Mit PrettyLinks k\u00f6nnen Sie verk\u00fcrzte Links erstellen mit <em>keine <\/em>der oben genannten Nachteile. Sie k\u00f6nnen dann auf Ihrer Website, Ihren Social-Media-Profilen und an jedem anderen Ort, an dem Sie f\u00fcr Ihre Marke werben, verwendet werden.<\/p>\n<p>Einen Pretty Link zu erstellen ist einfach. Sobald Sie <a href=\"https:\/\/prettylinks.com\/de\/docspretty-link-pro-installation\/\" target=\"_blank\" rel=\"noopener noreferrer\">gekauft, installiert und aktiviert<\/a> das Plugin, gehen Sie zu <em>PrettyLinks <\/em>&gt; <em>Neuen Link hinzuf\u00fcgen<\/em>. Hier k\u00f6nnen Sie Ihre <em>Ziel-URL<\/em>w\u00e4hlen Sie Ihr <em>Umleitung<\/em>und w\u00e4hlen Sie einen eindeutigen Slug (genannt a&nbsp;<em>H\u00fcbscher Link<\/em>):<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2282\" src=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1.jpg\" alt=\"Die Seite PrettyLinks Neue Verbindung hinzuf\u00fcgen\" width=\"800\" height=\"161\" srcset=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1.jpg 1662w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1-300x60.jpg 300w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1-1024x206.jpg 1024w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1-768x155.jpg 768w, https:\/\/prettylinks.com\/wp-content\/uploads\/2017\/08\/add-new-link-1-1536x310.jpg 1536w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Sobald Sie den Link erstellt haben, k\u00f6nnen Sie ihn \u00fcberall dort verwenden, wo Sie auch die <em>Ziel-URL.&nbsp;<\/em>Zum Beispiel auf Ihrer Website oder in Gastbeitr\u00e4gen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Schlussfolgerung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es besteht kein Zweifel, dass verk\u00fcrzte Links eine <a href=\"https:\/\/prettylinks.com\/de\/blog\/lesser-known-benefits-link-shortener\/\" target=\"_blank\" rel=\"noopener noreferrer\">zahlreiche Vorteile<\/a>. Doch genau <em>wie <\/em>Die Art und Weise, wie Sie sie k\u00fcrzen, kann bestimmen, wie Internetnutzer mit ihnen umgehen und welche Auswirkungen sie auf die <a href=\"https:\/\/prettylinks.com\/de\/blog\/high-quality-traffic-affiliate-marketing-site\/\" target=\"_blank\" rel=\"noopener noreferrer\">den Verkehr auf Ihrer Website<\/a>.<\/p>\n<p>In diesem Beitrag haben wir die drei h\u00e4ufigsten Nachteile von verk\u00fcrzten Links aufgezeigt und wie Sie diese vermeiden k\u00f6nnen. Zum Beispiel:<\/p>\n<ol>\n<li><strong>Internetnutzer k\u00f6nnen vorsichtig sein, wenn sie sich durchklicken.<\/strong> Dies l\u00e4sst sich durch ein angemessenes Branding beheben.<\/li>\n<li><strong>Sie k\u00f6nnen lange Umleitungsprozesse verursachen. <\/strong>Wenn Sie wissen, welche Weiterleitungen Sie verwenden sollten (und wann), k\u00f6nnen Sie ein schnelles Erlebnis gew\u00e4hrleisten.<\/li>\n<li><strong>Die Links funktionieren m\u00f6glicherweise nicht immer.<\/strong> Mit einem speziellen Linking-Tool k\u00f6nnen Sie sicherstellen, dass Ihre Links <em>immer<\/em> verf\u00fcgbar.<\/li>\n<\/ol>\n<p>Haben Sie Fragen zum Link-Shorting, oder wie <a href=\"https:\/\/prettylinks.com\/de\/about\/\" target=\"_blank\" rel=\"noopener noreferrer\">PrettyLinks<\/a> den Prozess verbessern k\u00f6nnen? Lassen Sie es uns in den Kommentaren unten wissen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Teilen von Links ist f\u00fcr viele Blogger, Websitebesitzer und Vermarkter eine Notwendigkeit. Lange Links k\u00f6nnen jedoch klobig, unattraktiv und in manchen F\u00e4llen auch wenig vertrauensw\u00fcrdig sein. Linkverk\u00fcrzer k\u00f6nnen helfen und haben viele Vorteile, aber sie haben auch ihre Schattenseiten. Wenn sie nicht richtig eingesetzt werden, k\u00f6nnen sie die Click-Through-Rates (CTRs) erheblich reduzieren und zu...<\/p>","protected":false},"author":11450,"featured_media":2608,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_strive_editorial_status":"not-started","_strive_copy_of":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[50,66],"tags":[23,13],"class_list":["post-2574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pretty-links","category-seo","tag-link-shortening","tag-pretty-link-pro"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"John Hughes\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"PrettyLinks\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"3 Downsides to Shortened Links (And How to Combat Them)\" \/>\n\t\t<meta property=\"og:description\" content=\"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1480\" \/>\n\t\t<meta property=\"og:image:height\" content=\"987\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-01-26T18:32:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-30T16:50:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"3 Downsides to Shortened Links (And How to Combat Them)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#blogposting\",\"name\":\"3 Downsides to Shortened Links (And How to Combat Them)\",\"headline\":\"3 Downsides to Shortened Links (And How to Combat Them)\",\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Combat-shorteners@2x.png\",\"width\":1480,\"height\":987},\"datePublished\":\"2018-01-26T18:32:50-07:00\",\"dateModified\":\"2019-12-30T16:50:46-07:00\",\"inLanguage\":\"de-DE\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#webpage\"},\"articleSection\":\"Pretty Links, SEO, link shortening, Pretty Links\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/category\\\/pretty-links\\\/#listItem\",\"name\":\"Pretty Links\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/category\\\/pretty-links\\\/#listItem\",\"position\":2,\"name\":\"Pretty Links\",\"item\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/category\\\/pretty-links\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#listItem\",\"name\":\"3 Downsides to Shortened Links (And How to Combat Them)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#listItem\",\"position\":3,\"name\":\"3 Downsides to Shortened Links (And How to Combat Them)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/category\\\/pretty-links\\\/#listItem\",\"name\":\"Pretty Links\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/#organization\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/author\\\/johnwordcandy-co\\\/\",\"name\":\"John Hughes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#authorImage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1787943643\",\"width\":96,\"height\":96,\"caption\":\"John Hughes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#webpage\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/\",\"name\":\"3 Downsides to Shortened Links (And How to Combat Them)\",\"description\":\"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/author\\\/johnwordcandy-co\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Combat-shorteners@2x.png\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#mainImage\",\"width\":1480,\"height\":987},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/blog\\\/downsides-to-shortened-links\\\/#mainImage\"},\"datePublished\":\"2018-01-26T18:32:50-07:00\",\"dateModified\":\"2019-12-30T16:50:46-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/\",\"name\":\"PrettyLinks\",\"description\":\"Top Affiliate Link & URL Shortener for WordPress\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/prettylinks.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>3 Downsides to Shortened Links (And How to Combat Them)<\/title>\n\n","aioseo_head_json":{"title":"3 Nachteile von verk\u00fcrzten Links (und wie man sie bek\u00e4mpft)","description":"Verk\u00fcrzte Links sind wirksame Elemente, die Sie in Ihre Verlinkungskampagnen einbauen k\u00f6nnen. Erfahren Sie, welche Nachteile eine unsachgem\u00e4\u00dfe Verwendung mit sich bringt und wie Sie diese vermeiden k\u00f6nnen.","canonical_url":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#blogposting","name":"3 Downsides to Shortened Links (And How to Combat Them)","headline":"3 Downsides to Shortened Links (And How to Combat Them)","author":{"@id":"https:\/\/prettylinks.com\/de\/blog\/author\/johnwordcandy-co\/#author"},"publisher":{"@id":"https:\/\/prettylinks.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png","width":1480,"height":987},"datePublished":"2018-01-26T18:32:50-07:00","dateModified":"2019-12-30T16:50:46-07:00","inLanguage":"de-DE","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#webpage"},"isPartOf":{"@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#webpage"},"articleSection":"Pretty Links, SEO, link shortening, Pretty Links"},{"@type":"BreadcrumbList","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de#listItem","position":1,"name":"Home","item":"https:\/\/prettylinks.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de\/blog\/category\/pretty-links\/#listItem","name":"Pretty Links"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de\/blog\/category\/pretty-links\/#listItem","position":2,"name":"Pretty Links","item":"https:\/\/prettylinks.com\/de\/blog\/category\/pretty-links\/","nextItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#listItem","name":"3 Downsides to Shortened Links (And How to Combat Them)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#listItem","position":3,"name":"3 Downsides to Shortened Links (And How to Combat Them)","previousItem":{"@type":"ListItem","@id":"https:\/\/prettylinks.com\/de\/blog\/category\/pretty-links\/#listItem","name":"Pretty Links"}}]},{"@type":"Organization","@id":"https:\/\/prettylinks.com\/de\/#organization","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","url":"https:\/\/prettylinks.com\/de\/"},{"@type":"Person","@id":"https:\/\/prettylinks.com\/de\/blog\/author\/johnwordcandy-co\/#author","url":"https:\/\/prettylinks.com\/de\/blog\/author\/johnwordcandy-co\/","name":"John Hughes","image":{"@type":"ImageObject","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#authorImage","url":"https:\/\/prettylinks.com\/wp-content\/litespeed\/avatar\/d2268e9193bd9486ff7dc3b65d739486.jpg?ver=1787943643","width":96,"height":96,"caption":"John Hughes"}},{"@type":"WebPage","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#webpage","url":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/","name":"3 Downsides to Shortened Links (And How to Combat Them)","description":"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/prettylinks.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#breadcrumblist"},"author":{"@id":"https:\/\/prettylinks.com\/de\/blog\/author\/johnwordcandy-co\/#author"},"creator":{"@id":"https:\/\/prettylinks.com\/de\/blog\/author\/johnwordcandy-co\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png","@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#mainImage","width":1480,"height":987},"primaryImageOfPage":{"@id":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/#mainImage"},"datePublished":"2018-01-26T18:32:50-07:00","dateModified":"2019-12-30T16:50:46-07:00"},{"@type":"WebSite","@id":"https:\/\/prettylinks.com\/de\/#website","url":"https:\/\/prettylinks.com\/de\/","name":"PrettyLinks","description":"Top Affiliate Link & URL Shortener for WordPress","inLanguage":"de-DE","publisher":{"@id":"https:\/\/prettylinks.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"PrettyLinks","og:type":"article","og:title":"3 Downsides to Shortened Links (And How to Combat Them)","og:description":"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.","og:url":"https:\/\/prettylinks.com\/de\/blog\/downsides-to-shortened-links\/","og:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png","og:image:secure_url":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png","og:image:width":1480,"og:image:height":987,"article:published_time":"2018-01-26T18:32:50+00:00","article:modified_time":"2019-12-30T16:50:46+00:00","twitter:card":"summary_large_image","twitter:title":"3 Downsides to Shortened Links (And How to Combat Them)","twitter:description":"Shortened links are effective elements you can add to your linking campaigns. Learn the common downsides of improper usage and how to avoid them.","twitter:image":"https:\/\/prettylinks.com\/wp-content\/uploads\/2018\/01\/Combat-shorteners@2x.png"},"aioseo_meta_data":{"post_id":"2574","title":null,"description":"Verk\u00fcrzte Links sind wirksame Elemente, die Sie in Ihre Verlinkungskampagnen einbauen k\u00f6nnen. Erfahren Sie, welche Nachteile eine unsachgem\u00e4\u00dfe Verwendung mit sich bringt und wie Sie diese vermeiden k\u00f6nnen.","keywords":[{"label":"downsides to shortened links","value":"downsides to shortened links"},{"label":"link building","value":"link building"},{"label":"SEO","value":"SEO"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-06-09 18:09:37","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 17:51:05","updated":"2026-06-09 18:09:37"},"_links":{"self":[{"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/posts\/2574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/users\/11450"}],"replies":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/comments?post=2574"}],"version-history":[{"count":0,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/posts\/2574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/media\/2608"}],"wp:attachment":[{"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/media?parent=2574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/categories?post=2574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prettylinks.com\/de\/wp-json\/wp\/v2\/tags?post=2574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}